{"id":1805,"date":"2023-08-24T03:28:18","date_gmt":"2023-08-23T19:28:18","guid":{"rendered":"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/"},"modified":"2023-08-24T03:28:18","modified_gmt":"2023-08-23T19:28:18","slug":"%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2","status":"publish","type":"post","link":"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/","title":{"rendered":"\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2"},"content":{"rendered":"<div><img decoding=\"async\" src=\"https:\/\/www.news.gov.hk\/chi\/2023\/08\/20230823\/20230823_180117_016\/images\/20230823201608841.jpg\"><\/p>\n<p>\uff08\u53ef\u6309<a>\u9019\u88cf<\/a>\u6536\u770b\u6574\u500b\u8a18\u8005\u6703\u7684\u624b\u8a9e\u7ffb\u8b6f\u77ed\u7247\u3002\uff09<\/p>\n<p>\u00a0<\/p>\n<p>\u7981\u6b62\u6e90\u81ea\u65e5\u672c\u798f\u5cf6\u7b49\u5341\u500b\u90fd\u6216\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7684\u98df\u7269\u5b89\u5168\u547d\u4ee4\u4eca\u65e5\u520a\u61b2\u3002\u653f\u5e9c\u5df2\u6210\u7acb\u8de8\u90e8\u9580\u5c08\u8cac\u5c0f\u7d44\u8a55\u4f30\u798f\u5cf6\u6838\u5ee2\u6c34\u6392\u653e\u8a08\u5283\u5c0d\u98df\u7269\u5b89\u5168\u7684\u5f71\u97ff\uff0c\u591a\u500b\u90e8\u9580\u6703\u52a0\u5f37\u6aa2\u6e2c\u65e5\u672c\u9032\u53e3\u98df\u54c1\u3001\u672c\u5730\u9b5a\u7522\u54c1\u548c\u672c\u6e2f\u6c34\u57df\u7684\u8f3b\u5c04\u6c34\u5e73\uff0c\u4fdd\u969c\u98df\u54c1\u5b89\u5168\uff0c\u7dad\u6301\u5e02\u6c11\u4fe1\u5fc3\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u8de8\u90e8\u9580\u5c08\u8cac\u5c0f\u7d44\u7531\u74b0\u5883\u53ca\u751f\u614b\u5c40\u3001\u98df\u7269\u74b0\u5883\u885e\u751f\u7f72\u3001\u98df\u7269\u5b89\u5168\u4e2d\u5fc3\u3001\u6f01\u8fb2\u81ea\u7136\u8b77\u7406\u7f72\u3001\u5929\u6587\u53f0\u3001\u885e\u751f\u7f72\u548c\u653f\u5e9c\u5316\u9a57\u6240\u7d44\u6210\u3002\u5c08\u8cac\u5c0f\u7d44\u4eca\u65e5\u8209\u884c\u8a18\u8005\u6703\uff0c\u4ea4\u4ee3\u52a0\u5f37\u4fdd\u969c\u98df\u7269\u5b89\u5168\u7684<a>\u5b89\u6392<\/a>\u548c\u7d30\u7bc0\uff0c\u4ee5\u53ca\u653f\u5e9c\u61c9\u5c0d\u65e5\u672c\u6392\u653e\u6838\u6c61\u6c34\u7684\u5de5\u4f5c\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u98df\u7269\u74b0\u5883\u885e\u751f\u7f72\u7f72\u9577\u694a\u78a7\u7b60\u8868\u793a\uff0c\u5979\u4eca\u65e5\u5df2\u884c\u4f7f\u300a\u98df\u7269\u5b89\u5168\u689d\u4f8b\u300b\u4e0b\u7684\u6b0a\u529b\u767c\u51fa\u76f8\u95dc\u98df\u7269\u5b89\u5168\u4ee4\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u6839\u64da\u547d\u4ee4\uff0c\u51e1\u6e90\u81ea\u6771\u4eac\u3001\u798f\u5cf6\u3001\u8328\u57ce\u3001\u5bae\u57ce\u3001\u5343\u8449\u3001\u7fa4\u99ac\u3001\u6803\u6728\u3001\u65b0\u6f5f\u3001\u9577\u91ce\u548c\u57fc\u7389\u5341\u500b\u90fd\u6216\u7e23\uff0c\u4e14\u65bc\u660e\u65e5\u96f6\u6642\u96f6\u5206\u6216\u4e4b\u5f8c\u6536\u7a6b\u3001\u88fd\u9020\u3001\u52a0\u5de5\u6216\u5305\u88dd\u7684\u6d3b\u751f\u3001\u51b7\u51cd\u3001\u51b7\u85cf\u3001\u4e7e\u88fd\u6216\u4ee5\u5176\u4ed6\u65b9\u5f0f\u4fdd\u5b58\u7684\u6c34\u7522\u3001\u6d77\u9e7d\uff0c\u4ee5\u53ca\u672a\u7d93\u52a0\u5de5\u6216\u7d93\u52a0\u5de5\u7684\u6d77\u85fb\uff0c\u4e00\u5f8b\u7981\u6b62\u8f38\u5165\u9999\u6e2f\u548c\u5728\u6e2f\u5883\u5167\u4f9b\u61c9\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u81f3\u65bc\u5176\u4ed6\u672a\u88ab\u7981\u6b62\u8f38\u5165\u9999\u6e2f\uff0c\u548c\u5728\u9999\u6e2f\u5883\u5167\u4f9b\u61c9\u7684\u65e5\u672c\u6c34\u7522\u54c1\u3001\u6d77\u9e7d\uff0c\u4ee5\u53ca\u672a\u7d93\u52a0\u5de5\u6216\u7d93\u52a0\u5de5\u7684\u6d77\u85fb\uff0c\u98df\u5b89\u4e2d\u5fc3\u6703\u9032\u884c\u5168\u9762\u8f3b\u5c04\u6c34\u5e73\u6e2c\u8a66\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u98df\u7269\u5b89\u5168\u5c08\u54e1\u9ec3\u5b8f\u8868\u793a\uff0c\u98df\u5b89\u4e2d\u5fc3\u81ea4\u6708\u8d77\u9010\u6b65\u52a0\u5f37\u5c0d\u65e5\u672c\u9032\u53e3\u98df\u54c1\u7684\u8f3b\u5c04\u6aa2\u6e2c\uff0c\u7279\u5225\u589e\u52a0\u5c0d\u6c34\u7522\u54c1\u7684\u6aa2\u6e2c\u3002\u81ea6\u6708\u4e2d\u81f3\u4eca\uff0c\u98df\u5b89\u4e2d\u5fc3\u5927\u7d04\u6aa2\u6e2c10,357\u500b\u65e5\u672c\u9032\u53e3\u98df\u54c1\u6a23\u672c\uff0c\u7576\u4e2d\u903e\u534a\u5c6c\u6c34\u7522\u54c1\uff0c\u6b64\u6578\u91cf\u5df2\u7b49\u540c\u53bb\u5e74\u5168\u5e74\u7684\u6aa2\u6e2c\u91cf\u3002\u5979\u5f37\u8abf\uff0c\u73fe\u6642\u6240\u6709\u6c34\u7522\u54c1\u90fd\u7d93\u904e\u98df\u5b89\u4e2d\u5fc3\u6aa2\u6e2c\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u5979\u7e8c\u8aaa\uff0c\u98df\u5b89\u4e2d\u5fc3\u91cd\u8996\u696d\u754c\uff0c\u6703\u8207\u4ed6\u5011\u4fdd\u6301\u7dca\u5bc6\u6e9d\u901a\uff0c\u4eca\u65e9\u5df2\u70ba\u696d\u754c\u8209\u884c\u5169\u5834\u7db2\u4e0a\u7c21\u4ecb\u6703\uff0c\u903e700\u4eba\u53c3\u8207\uff0c\u7a0d\u5f8c\u98df\u5b89\u4e2d\u5fc3\u6703\u518d\u8fa6\u7b2c\u4e09\u5834\u7c21\u4ecb\u6703\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u98df\u5b89\u4e2d\u5fc3\u6bcf\u500b\u5de5\u4f5c\u5929\u6703\u5728<a>\u7db2\u9801<\/a>\u516c\u5e03\u6709\u95dc\u65e5\u672c\u9032\u53e3\u98df\u54c1\u6a23\u672c\u8f3b\u5c04\u6aa2\u6e2c\u7d50\u679c\uff0c\u8cc7\u6599\u6703\u8f49\u8f09\u74b0\u5883\u53ca\u751f\u614b\u5c40\u6bcf\u500b\u5de5\u4f5c\u5929\u767c\u5e03\u7684\u65b0\u805e\u516c\u5831\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u6f01\u8b77\u7f72\u52a9\u7406\u7f72\u9577\u9ece\u5b58\u5fd7\u8868\u793a\uff0c\u7f72\u65b9\u660e\u5929\u8d77\u52a0\u5f37\u672c\u5730\u9b5a\u7522\u54c1\u8f3b\u5c04\u6c34\u5e73\u7684\u76e3\u6e2c\uff0c\u6703\u6aa2\u6e2c\u9b5a\u985e\u7d71\u71df\u8655\u9b5a\u985e\u6279\u767c\u5e02\u5834\u6279\u92b7\u7684\u6355\u6488\u9b5a\u7522\u54c1\uff0c\u4e26\u5728\u9999\u6e2f\u6c34\u57df\u3001\u9b5a\u985e\u990a\u6b96\u5340\u63a1\u96c6\u6a23\u672c\u9032\u884c\u76e3\u6e2c\u3002\u6aa2\u6e2c\u983b\u7387\u7531\u73fe\u6642\u6bcf\u6708\u4e00\u6b21\uff0c\u589e\u81f3\u6bcf\u65e5\u4e00\u6b21\uff0c\u6aa2\u6e2c\u7d50\u679c\u6bcf\u65e5\u5728\u7f72\u65b9<a>\u7db2\u7ad9<\/a>\u516c\u5e03\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u5929\u6587\u53f0\u52a9\u7406\u53f0\u9577\u674e\u7acb\u4fe1\u8aaa\uff0c\u5929\u6587\u53f0\u4e00\u76f4\u76e3\u6e2c\u672c\u6e2f\u7684\u74b0\u5883\u8f3b\u5c04\u6c34\u5e73\uff0c\u5305\u62ec\u6bcf\u5b63\u5f9e\u672c\u6e2f\u6c34\u57df\u62bd\u53d6\u6d77\u6c34\u6a23\u672c\uff0c\u6e2c\u91cf\u7576\u4e2d\u7684\u6c1a\u548c\u4eba\u5de5\u4f3d\u99ac\u653e\u5c04\u6027\u6838\u7d20\u542b\u91cf\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u56e0\u61c9\u65e5\u672c\u798f\u5cf6\u6838\u6c61\u6c34\u6392\u653e\uff0c\u5929\u6587\u53f0\u4e0a\u6708\u958b\u59cb\u52a0\u5bc6\u672c\u6e2f\u6c34\u57df\u6d77\u6c34\u6a23\u672c\u7684\u8f3b\u5c04\u76e3\u6e2c\u81f3\u7d04\u6bcf\u6708\u4e00\u6b21\uff0c\u5982\u6709\u9700\u8981\u6703\u61c9\u56e0\u60c5\u6cc1\u8abf\u6574\u6b21\u6578\uff0c\u76e3\u6e2c\u7d50\u679c\u6703\u5728\u90e8\u9580<a>\u7db2\u7ad9<\/a>\u516c\u5e03\u3002<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\uff08\u53ef\u6309\u9019\u88cf\u6536\u770b\u6574\u500b\u8a18\u8005\u6703\u7684\u624b\u8a9e\u7ffb\u8b6f\u77ed\u7247\u3002\uff09 \u00a0 \u7981\u6b62\u6e90\u81ea\u65e5\u672c\u798f\u5cf6\u7b49\u5341\u500b\u90fd\u6216\u7e23\u6c34\u7522&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9,2],"tags":[27,26,16],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2 - \u9999\u6e2f\u8cfc\u7269\u7db2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2 - \u9999\u6e2f\u8cfc\u7269\u7db2\" \/>\n<meta property=\"og:description\" content=\"\uff08\u53ef\u6309\u9019\u88cf\u6536\u770b\u6574\u500b\u8a18\u8005\u6703\u7684\u624b\u8a9e\u7ffb\u8b6f\u77ed\u7247\u3002\uff09 \u00a0 \u7981\u6b62\u6e90\u81ea\u65e5\u672c\u798f\u5cf6\u7b49\u5341\u500b\u90fd\u6216\u7e23\u6c34\u7522...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2\/\" \/>\n<meta property=\"og:site_name\" content=\"\u9999\u6e2f\u8cfc\u7269\u7db2\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-23T19:28:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.news.gov.hk\/chi\/2023\/08\/20230823\/20230823_180117_016\/images\/20230823201608841.jpg\" \/>\n<meta name=\"author\" content=\"cloudian-support\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.news.gov.hk\/chi\/2023\/08\/20230823\/20230823_180117_016\/images\/20230823201608841.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cloudian-support\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/\",\"url\":\"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/\",\"name\":\"\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2 - \u9999\u6e2f\u8cfc\u7269\u7db2\",\"isPartOf\":{\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/#website\"},\"datePublished\":\"2023-08-23T19:28:18+00:00\",\"dateModified\":\"2023-08-23T19:28:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/4999a23b13895195840c767d0bb2d6dd\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/#breadcrumb\"},\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\/\/www.buyinghongkong.com\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/#website\",\"url\":\"https:\/\/www.buyinghongkong.com\/news\/\",\"name\":\"\u9999\u6e2f\u8cfc\u7269\u7db2\",\"description\":\"https:\/\/www.buyinghongkong.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.buyinghongkong.com\/news\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/4999a23b13895195840c767d0bb2d6dd\",\"name\":\"cloudian-support\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1366ba2b659aec08306bb704e2af307b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1366ba2b659aec08306bb704e2af307b?s=96&d=mm&r=g\",\"caption\":\"cloudian-support\"},\"sameAs\":[\"https:\/\/www.bud.org.hk\/web\"],\"url\":false}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2 - \u9999\u6e2f\u8cfc\u7269\u7db2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2\/","og_locale":"zh_TW","og_type":"article","og_title":"\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2 - \u9999\u6e2f\u8cfc\u7269\u7db2","og_description":"\uff08\u53ef\u6309\u9019\u88cf\u6536\u770b\u6574\u500b\u8a18\u8005\u6703\u7684\u624b\u8a9e\u7ffb\u8b6f\u77ed\u7247\u3002\uff09 \u00a0 \u7981\u6b62\u6e90\u81ea\u65e5\u672c\u798f\u5cf6\u7b49\u5341\u500b\u90fd\u6216\u7e23\u6c34\u7522...","og_url":"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2\/","og_site_name":"\u9999\u6e2f\u8cfc\u7269\u7db2","article_published_time":"2023-08-23T19:28:18+00:00","og_image":[{"url":"https:\/\/www.news.gov.hk\/chi\/2023\/08\/20230823\/20230823_180117_016\/images\/20230823201608841.jpg"}],"author":"cloudian-support","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.news.gov.hk\/chi\/2023\/08\/20230823\/20230823_180117_016\/images\/20230823201608841.jpg","twitter_misc":{"Written by":"cloudian-support"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/","url":"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/","name":"\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2 - \u9999\u6e2f\u8cfc\u7269\u7db2","isPartOf":{"@id":"https:\/\/www.buyinghongkong.com\/news\/#website"},"datePublished":"2023-08-23T19:28:18+00:00","dateModified":"2023-08-23T19:28:18+00:00","author":{"@id":"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/4999a23b13895195840c767d0bb2d6dd"},"breadcrumb":{"@id":"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buyinghongkong.com\/news\/2023\/08\/%e6%97%a5%e6%9c%ac%e5%8d%81%e9%83%bd%e7%b8%a3%e6%b0%b4%e7%94%a2%e5%93%81%e9%80%b2%e5%8f%a3%e7%a6%81%e4%bb%a4%e5%88%8a%e6%86%b2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/www.buyinghongkong.com\/news\/"},{"@type":"ListItem","position":2,"name":"\u65e5\u672c\u5341\u90fd\u7e23\u6c34\u7522\u54c1\u9032\u53e3\u7981\u4ee4\u520a\u61b2"}]},{"@type":"WebSite","@id":"https:\/\/www.buyinghongkong.com\/news\/#website","url":"https:\/\/www.buyinghongkong.com\/news\/","name":"\u9999\u6e2f\u8cfc\u7269\u7db2","description":"https:\/\/www.buyinghongkong.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buyinghongkong.com\/news\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-TW"},{"@type":"Person","@id":"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/4999a23b13895195840c767d0bb2d6dd","name":"cloudian-support","image":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1366ba2b659aec08306bb704e2af307b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1366ba2b659aec08306bb704e2af307b?s=96&d=mm&r=g","caption":"cloudian-support"},"sameAs":["https:\/\/www.bud.org.hk\/web"],"url":false}]}},"_links":{"self":[{"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/posts\/1805"}],"collection":[{"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/comments?post=1805"}],"version-history":[{"count":0,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/posts\/1805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/media\/1806"}],"wp:attachment":[{"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/media?parent=1805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/categories?post=1805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/tags?post=1805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}