{"id":11896,"date":"2024-12-15T03:10:20","date_gmt":"2024-12-14T19:10:20","guid":{"rendered":"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/"},"modified":"2024-12-15T03:10:20","modified_gmt":"2024-12-14T19:10:20","slug":"%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7","status":"publish","type":"post","link":"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/","title":{"rendered":"\u724c\u8b49\u6613\u63a8\u51fa \u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167"},"content":{"rendered":"<div><img decoding=\"async\" src=\"https:\/\/www.news.gov.hk\/chi\/2024\/12\/20241214\/20241214_102857_272\/images\/20241214104827719.jpg\"><\/p>\n<p>\u904b\u8f38\u7f72\u4eca\u65e5\u63a8\u51fa\u7db2\u4e0a\u96fb\u5b50\u724c\u7167\u5e73\u53f0\u300c<a>\u724c\u8b49\u6613<\/a>\u300d\uff0c\u63d0\u4f9b\u4e00\u7ad9\u5f0f\u670d\u52d9\uff0c\u4fbf\u5229\u767b\u8a18\u8eca\u4e3b\u548c\u53f8\u6a5f\u7e8c\u9818\u8eca\u8f1b\u724c\u7167\u548c\u99d5\u99db\u57f7\u7167\uff0c\u4ee5\u53ca\u67e5\u95b1\u724c\u8b49\u8cc7\u6599\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u5e02\u6c11\u900f\u904e\u300c\u667a\u65b9\u4fbf\u300d\u767b\u8a18\u70ba\u300c\u724c\u8b49\u6613\u300d\u7528\u6236\u5f8c\uff0c\u53ef\u96a8\u6642\u67e5\u95b1\u99d5\u99db\u57f7\u7167\u3001\u53ef\u99d5\u99db\u8eca\u8f1b\u985e\u5225\u548c\u57f7\u7167\u5230\u671f\u65e5\uff1b\u9055\u4f8b\u99d5\u99db\u8a18\u5206\u7d00\u9304\uff1b\u6301\u6709\u7684\u767b\u8a18\u8eca\u8f1b\u53ca\u724c\u7167\u5230\u671f\u65e5\uff0c\u4e5f\u53ef\u9078\u64c7\u63a5\u6536\u99d5\u99db\u57f7\u7167\u548c\u8eca\u8f1b\u724c\u7167\u7684\u7e8c\u9818\u63d0\u793a\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u5373\u65e5\u8d77\uff0c\u9999\u6e2f\u8eab\u4efd\u8b49\u6301\u6709\u4eba\u53ef\u4f7f\u7528\u300c\u667a\u65b9\u4fbf\u300d\u767b\u8a18\u70ba\u300c\u724c\u8b49\u6613\u300d\u7528\u6236\u3002\u975e\u9999\u6e2f\u8eab\u4efd\u8b49\u6301\u6709\u4eba\uff0c\u5305\u62ec\u8b77\u7167\u6301\u6709\u4eba\u3001\u5f80\u4f86\u6e2f\u6fb3\u901a\u884c\u8b49\u6301\u6709\u4eba\u3001\u516c\u53f8\u3001\u6a5f\u69cb\uff0c\u5247\u53ef\u4f7f\u7528\u6578\u78bc\u8b49\u66f8\u6216\u5728\u904b\u8f38\u7f72\u767b\u8a18\u7684\u96fb\u5b50\u806f\u7d61\u65b9\u5f0f\u8a3b\u518a\u5e33\u6236\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u904b\u8f38\u7f72\u8868\u793a\uff0c\u63a8\u51fa\u300c\u724c\u8b49\u6613\u300d\u5f8c\uff0c\u767b\u8a18\u8eca\u4e3b\u548c\u53f8\u6a5f\u53ef\u66f4\u8f15\u9b06\u7ba1\u7406\u540d\u4e0b\u7684\u724c\u8b49\u53ca\u8eca\u8f1b\uff0c\u96a8\u6642\u96a8\u5730\u67e5\u95b1\u8cc7\u6599\u3002\u7e8c\u9818\u63d0\u793a\u529f\u80fd\u4e5f\u53ef\u5728\u767b\u8a18\u7528\u6236\u7684\u724c\u8b49\u5feb\u5c07\u5230\u671f\u6642\u767c\u51fa\u63d0\u793a\uff0c\u4e26\u8b93\u8eca\u4e3b\u53ca\u99d5\u99db\u4eba\u58eb\u65bc\u7db2\u4e0a\u7e8c\u9818\u724c\u7167\u3002<\/p>\n<p>\u00a0<\/p>\n<p>\u7f72\u65b9\u53c8\u63d0\u5230\uff0c\u300c\u724c\u8b49\u6613\u300d\u660e\u5e74\u7b2c\u4e8c\u5b63\u63a8\u51fa\u5176\u4ed6\u529f\u80fd\u5f8c\uff0c\u7528\u6236\u53ef\u4f7f\u7528\u81ea\u52d5\u586b\u8868\u529f\u80fd\u63d0\u4ea4\u7db2\u4e0a\u724c\u7167\u7533\u8acb\u3001\u67e5\u8a62\u7533\u8acb\u9032\u5ea6\u548c\u7d50\u679c\u3001\u7db2\u4e0a\u9810\u7d04\u99d5\u99db\u8003\u8a66\uff0c\u4e26\u67e5\u95b1\u5404\u985e\u8a31\u53ef\u8b49\u8cc7\u6599\u3002<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u904b\u8f38\u7f72\u4eca\u65e5\u63a8\u51fa\u7db2\u4e0a\u96fb\u5b50\u724c\u7167\u5e73\u53f0\u300c\u724c\u8b49\u6613\u300d\uff0c\u63d0\u4f9b\u4e00\u7ad9\u5f0f\u670d\u52d9\uff0c\u4fbf\u5229\u767b\u8a18\u8eca\u4e3b\u548c\u53f8\u6a5f\u7e8c\u9818&#8230;<\/p>\n","protected":false},"author":1,"featured_media":11897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[12,2],"tags":[20,21,16],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u724c\u8b49\u6613\u63a8\u51fa \u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167 - \u9999\u6e2f\u8cfc\u7269\u7db2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/\u724c\u8b49\u6613\u63a8\u51fa-\u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u724c\u8b49\u6613\u63a8\u51fa \u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167 - \u9999\u6e2f\u8cfc\u7269\u7db2\" \/>\n<meta property=\"og:description\" content=\"\u904b\u8f38\u7f72\u4eca\u65e5\u63a8\u51fa\u7db2\u4e0a\u96fb\u5b50\u724c\u7167\u5e73\u53f0\u300c\u724c\u8b49\u6613\u300d\uff0c\u63d0\u4f9b\u4e00\u7ad9\u5f0f\u670d\u52d9\uff0c\u4fbf\u5229\u767b\u8a18\u8eca\u4e3b\u548c\u53f8\u6a5f\u7e8c\u9818...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/\u724c\u8b49\u6613\u63a8\u51fa-\u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167\/\" \/>\n<meta property=\"og:site_name\" content=\"\u9999\u6e2f\u8cfc\u7269\u7db2\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-14T19:10:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.news.gov.hk\/chi\/2024\/12\/20241214\/20241214_102857_272\/images\/20241214104827719.jpg\" \/>\n<meta name=\"author\" content=\"cloudian-support\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.news.gov.hk\/chi\/2024\/12\/20241214\/20241214_102857_272\/images\/20241214104827719.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cloudian-support\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/\",\"url\":\"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/\",\"name\":\"\u724c\u8b49\u6613\u63a8\u51fa \u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167 - \u9999\u6e2f\u8cfc\u7269\u7db2\",\"isPartOf\":{\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/#website\"},\"datePublished\":\"2024-12-14T19:10:20+00:00\",\"dateModified\":\"2024-12-14T19:10:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/4999a23b13895195840c767d0bb2d6dd\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/#breadcrumb\"},\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\/\/www.buyinghongkong.com\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u724c\u8b49\u6613\u63a8\u51fa \u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/#website\",\"url\":\"https:\/\/www.buyinghongkong.com\/news\/\",\"name\":\"\u9999\u6e2f\u8cfc\u7269\u7db2\",\"description\":\"https:\/\/www.buyinghongkong.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.buyinghongkong.com\/news\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/4999a23b13895195840c767d0bb2d6dd\",\"name\":\"cloudian-support\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-TW\",\"@id\":\"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1366ba2b659aec08306bb704e2af307b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1366ba2b659aec08306bb704e2af307b?s=96&d=mm&r=g\",\"caption\":\"cloudian-support\"},\"sameAs\":[\"https:\/\/www.bud.org.hk\/web\"],\"url\":false}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u724c\u8b49\u6613\u63a8\u51fa \u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167 - \u9999\u6e2f\u8cfc\u7269\u7db2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/\u724c\u8b49\u6613\u63a8\u51fa-\u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167\/","og_locale":"zh_TW","og_type":"article","og_title":"\u724c\u8b49\u6613\u63a8\u51fa \u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167 - \u9999\u6e2f\u8cfc\u7269\u7db2","og_description":"\u904b\u8f38\u7f72\u4eca\u65e5\u63a8\u51fa\u7db2\u4e0a\u96fb\u5b50\u724c\u7167\u5e73\u53f0\u300c\u724c\u8b49\u6613\u300d\uff0c\u63d0\u4f9b\u4e00\u7ad9\u5f0f\u670d\u52d9\uff0c\u4fbf\u5229\u767b\u8a18\u8eca\u4e3b\u548c\u53f8\u6a5f\u7e8c\u9818...","og_url":"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/\u724c\u8b49\u6613\u63a8\u51fa-\u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167\/","og_site_name":"\u9999\u6e2f\u8cfc\u7269\u7db2","article_published_time":"2024-12-14T19:10:20+00:00","og_image":[{"url":"https:\/\/www.news.gov.hk\/chi\/2024\/12\/20241214\/20241214_102857_272\/images\/20241214104827719.jpg"}],"author":"cloudian-support","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.news.gov.hk\/chi\/2024\/12\/20241214\/20241214_102857_272\/images\/20241214104827719.jpg","twitter_misc":{"Written by":"cloudian-support"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/","url":"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/","name":"\u724c\u8b49\u6613\u63a8\u51fa \u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167 - \u9999\u6e2f\u8cfc\u7269\u7db2","isPartOf":{"@id":"https:\/\/www.buyinghongkong.com\/news\/#website"},"datePublished":"2024-12-14T19:10:20+00:00","dateModified":"2024-12-14T19:10:20+00:00","author":{"@id":"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/4999a23b13895195840c767d0bb2d6dd"},"breadcrumb":{"@id":"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buyinghongkong.com\/news\/2024\/12\/%e7%89%8c%e8%ad%89%e6%98%93%e6%8e%a8%e5%87%ba-%e4%be%bf%e5%88%a9%e8%bb%8a%e4%b8%bb%e7%ba%8c%e9%a0%98%e7%89%8c%e7%85%a7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/www.buyinghongkong.com\/news\/"},{"@type":"ListItem","position":2,"name":"\u724c\u8b49\u6613\u63a8\u51fa \u4fbf\u5229\u8eca\u4e3b\u7e8c\u9818\u724c\u7167"}]},{"@type":"WebSite","@id":"https:\/\/www.buyinghongkong.com\/news\/#website","url":"https:\/\/www.buyinghongkong.com\/news\/","name":"\u9999\u6e2f\u8cfc\u7269\u7db2","description":"https:\/\/www.buyinghongkong.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buyinghongkong.com\/news\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-TW"},{"@type":"Person","@id":"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/4999a23b13895195840c767d0bb2d6dd","name":"cloudian-support","image":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/www.buyinghongkong.com\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1366ba2b659aec08306bb704e2af307b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1366ba2b659aec08306bb704e2af307b?s=96&d=mm&r=g","caption":"cloudian-support"},"sameAs":["https:\/\/www.bud.org.hk\/web"],"url":false}]}},"_links":{"self":[{"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/posts\/11896"}],"collection":[{"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/comments?post=11896"}],"version-history":[{"count":0,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/posts\/11896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/media\/11897"}],"wp:attachment":[{"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/media?parent=11896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/categories?post=11896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buyinghongkong.com\/news\/wp-json\/wp\/v2\/tags?post=11896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}